{"id":2476,"date":"2023-12-01T07:30:25","date_gmt":"2023-12-01T06:30:25","guid":{"rendered":"https:\/\/staysafe.bazl.admin.ch\/?p=2476"},"modified":"2024-02-29T10:01:52","modified_gmt":"2024-02-29T09:01:52","slug":"eine-schiefe-sache-landung-bei-seitenwind","status":"publish","type":"post","link":"https:\/\/staysafe.aero\/de\/eine-schiefe-sache-landung-bei-seitenwind\/","title":{"rendered":"Landung bei Seitenwind (2\/3) &#8211; Landetechniken"},"content":{"rendered":"<p><\/p>\n<p data-pm-slice=\"1 1 []\">Mitte November ist das Sturmtief \u00abFrederico\u00bb mit Windgeschwindigkeiten von bis zu 130 km\/h \u00fcber unser Land gefegt. Da hat sich hoffentlich keiner von euch in die Luft gewagt. Gerade in den Herbst- und Wintermonaten sind St\u00fcrme und windige Wetterverh\u00e4ltnisse wiederholt anzutreffen. F\u00fcr die etwas ruhigeren, aber dennoch windigen Situationen, ist es wichtig, dass sich<strong> Piloten mit Landetechniken bei Seitenwindverh\u00e4ltnissen auseinandersetzen und diese \u00fcben.<\/strong><\/p>\n<p>Landen bei Seitenwind (Engl. crosswind) ist ohne Frage eine anspruchsvolle Angelegenheit. Zum einen ver\u00e4ndert sich im Anflug der Wind in Richtung und St\u00e4rke und man ist gezwungen, st\u00e4ndig Korrekturen durchzuf\u00fchren, um das Flugzeug auf der Anfluggrundlinie zu halten, zum anderen nimmt mit geringer werdender Anfluggeschwindigkeit die Wirkung der Ruder ab.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2482 alignleft\" src=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/crab_de.png\" alt=\"\" width=\"319\" height=\"458\" srcset=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/crab_de.png 422w, https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/crab_de-209x300.png 209w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Es muss also eine Methode angewandt werden, mit der trotz starkem Seitenwind der Flugweg \u00fcber Grund entlang der Anflugachse der Landebahn gehalten wird. Dazu gibt es <strong>zwei Methoden, die Slip- und Crap-Methode<\/strong>. Beim \u00ab<strong>Crab<\/strong>\u00bb erfolgt der Anflug mit einem Vorhaltewinkel bis kurz vor dem Aufsetzen. Erst unmittelbar vor dem Aufsetzen wird das Flugzeug mit dem Seitenruder ausgerichtet.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2481 alignright\" src=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/slip_de.png\" alt=\"\" width=\"316\" height=\"270\" srcset=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/slip_de.png 471w, https:\/\/staysafe.aero\/wp-content\/uploads\/2019\/02\/slip_de-300x257.png 300w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Beim \u00ab<strong>Slip<\/strong>\u00bb senkt man mit dem Querruder die Fl\u00e4che auf der windzugewandten Seite (Luv) und tritt zugleich in Gegenrichtung so ins Seitenruder, dass die Maschine keine Kurve steuert, sondern weiter geradeaus fliegt. So slippt man mit gekreuzten Rudern gegen den Seitenwind an, gleicht damit die Seitw\u00e4rtsbewegung der Luft relativ zum Boden aus und h\u00e4lt das Flugzeug auf der verl\u00e4ngerten Achse der Landebahn. Gleichzeitig l\u00e4sst sich mit dem Seitenruder die L\u00e4ngsachse der Maschine schr\u00e4g zur Landebahn halten. Kurz vor dem Aufsetzen wird der Seitengleitflug ausgeleitet, die L\u00e4ngsachse wird wieder auf die Center Line ausgerichtet.<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00fcr diese besonders anspruchsvollen Landetechniken empfehlen wir euch, diese mindestens einmal im Jahr mit eurem Fluglehrer (CFI) zu \u00fcben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Erkl\u00e4rvideo und Simulation<\/strong><br \/>\nZur Veranschaulichung und Trocken\u00fcbungen reichen schon mal der <a href=\"https:\/\/www.faa.gov\/news\/safety_briefing\/2016\/media\/SE_Topic_16-03.pdf\" target=\"_blank\" rel=\"noopener lightbox-video-0\">Newsletter der FAA Aviation Safety<\/a>, das <a href=\"https:\/\/lernprogramm.sphair.ch\/de\/platzverkehr-anflug-landung\/seitenwindanflug-und--landung\" target=\"_blank\" rel=\"noopener lightbox-video-0\">Kapitel Ausschweben und Aufsetzen mit Seitenwind von SPHAIR (inkl. Simulation) <\/a>oder das <a href=\"https:\/\/www.youtube.com\/watch?v=AF0Su06eBLs\" target=\"_blank\" rel=\"noopener lightbox-video-0\">Video der AOPA<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Happy landings.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lernprogramm.sphair.ch\/de\/platzverkehr-anflug-landung\/seitenwindanflug-und--landung\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4776\" src=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2023\/12\/Screenshot-2023-12-01-082008.jpg\" alt=\"\" width=\"1270\" height=\"758\" srcset=\"https:\/\/staysafe.aero\/wp-content\/uploads\/2023\/12\/Screenshot-2023-12-01-082008.jpg 1270w, https:\/\/staysafe.aero\/wp-content\/uploads\/2023\/12\/Screenshot-2023-12-01-082008-300x179.jpg 300w, https:\/\/staysafe.aero\/wp-content\/uploads\/2023\/12\/Screenshot-2023-12-01-082008-1024x611.jpg 1024w, https:\/\/staysafe.aero\/wp-content\/uploads\/2023\/12\/Screenshot-2023-12-01-082008-768x458.jpg 768w\" sizes=\"auto, (max-width: 1270px) 100vw, 1270px\" \/><\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"Flight Training - Cross-wind Landings Video from AOPA.\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/AF0Su06eBLs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>#flighttraining #flightplanning #crosswindlandingd #vfrfligths #vfr #aviationweather #aviation #avsafety #aviationgeek #weareGA #pilots #flying #generalaviation #airoperation #SafetyCulture<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Mitte November ist das Sturmtief \u00abFrederico\u00bb mit Windgeschwindigkeiten von bis zu 130 km\/h \u00fcber unser Land gefegt. Da hat sich [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[488,492,497,503,504,506,511,1,513,9,10,13,31,159,356,486,487],"tags":[260,293,298,300],"class_list":["post-2476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultraleicht-ecolight","category-eigenbau","category-airmanship-become-a-better-pilot","category-unfaelle-und-vorfaelle","category-pilot-ich-bin","category-fluglehrerin","category-aviation-accidents-and-incidents","category-home-teaser","category-safety-medien-unterlagen","category-pilot","category-flugzeug","category-aktuell","category-operation","category-lesson-learned","category-video","category-motorflug","category-segelflug","tag-flugplatz","tag-loss-of-control-in-flight","tag-air-operations","tag-motorflug"],"_links":{"self":[{"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/posts\/2476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/comments?post=2476"}],"version-history":[{"count":20,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/posts\/2476\/revisions"}],"predecessor-version":[{"id":4781,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/posts\/2476\/revisions\/4781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/media\/837"}],"wp:attachment":[{"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/media?parent=2476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/categories?post=2476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staysafe.aero\/de\/wp-json\/wp\/v2\/tags?post=2476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}