{"id":516,"count":15,"description":"Cette rubrique sert \u00e0 l'\u00e9change d'informations et comprend les dates importantes de la sc\u00e8ne GA ainsi que des liens, des indications et des offres pertinentes pour l'aviation dans le domaine de la s\u00e9curit\u00e9.\r\n\r\nSi tu souhaites que des dates ou des informations soient mentionn\u00e9es ou modifi\u00e9es ici, contacte-nous \u00e0 l'adresse staysafe@bazl.admin.ch","link":"https:\/\/staysafe.aero\/fr\/category\/rubriken\/events-scene-links\/","name":"\u00c9v\u00e9nements, sc\u00e8nes et liens","slug":"events-scene-links","taxonomy":"category","parent":509,"meta":[],"_links":{"self":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/categories\/516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/categories\/509"}],"wp:post_type":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/posts?categories=516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}