{"id":3636,"date":"2021-03-04T11:32:05","date_gmt":"2021-03-04T10:32:05","guid":{"rendered":"https:\/\/staysafe.admin.ch\/?p=3636"},"modified":"2021-03-04T11:32:05","modified_gmt":"2021-03-04T10:32:05","slug":"umfrage-wie-bereitet-ihr-euch-auf-die-flugsaison-vor","status":"publish","type":"post","link":"https:\/\/staysafe.aero\/fr\/umfrage-wie-bereitet-ihr-euch-auf-die-flugsaison-vor\/","title":{"rendered":"Comment vous pr\u00e9parez-vous \u00e0 la saison a\u00e9ronautique ?"},"content":{"rendered":"<p>Lorsque les premiers perce-neige pointent le bout de leurs clochettes et que les jours rallongent, le d\u00e9but de la saison a\u00e9ronautique n\u2019est pas loin. Or, la reprise n\u2019est pas sans risques. Pendant la saison d\u2019hiver, les pilotes sont un peu \u00e0 court de pratique, les r\u00e9flexes sont rouill\u00e9s et les proc\u00e9dures laborieuses. Autant de sources d\u2019erreurs potentielles qui, mises bout \u00e0 bout, peuvent conduire \u00e0 l\u2019accident.<\/p>\n<p>Contrairement aux pilotes de ligne, les pilotes priv\u00e9s sont seuls responsables de la s\u00e9curit\u00e9 du vol. Ils portent en quelque sorte \u00e0 la fois la casquette de pilote et de copilote. Il faut donc apporter un soin non seulement \u00e0 la pr\u00e9paration des appareils, mais aussi \u00e0 sa propre pr\u00e9paration en vue de la saison a\u00e9ronautique. De nombreuses approches sont possibles. Et vous ? Comment vous pr\u00e9parez-vous \u00e0 la reprise de la saison a\u00e9ronautique ? <strong><a href=\"https:\/\/findmind.ch\/c\/ziR1-k3mA\">Veuillez prendre deux minutes pour participer \u00e0 notre enqu\u00eate.<\/a> <\/strong>Merci beaucoup !<\/p>","protected":false},"excerpt":{"rendered":"<p>Lorsque les premiers perce-neige pointent le bout de leurs clochettes et que les jours rallongent, le d\u00e9but de la saison [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":3637,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[9,13,30,31,1],"tags":[210],"class_list":["post-3636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pilot","category-aktuell","category-diverses","category-operation","category-home-teaser","tag-flugvorbereitung"],"_links":{"self":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/posts\/3636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/comments?post=3636"}],"version-history":[{"count":1,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/posts\/3636\/revisions"}],"predecessor-version":[{"id":3638,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/posts\/3636\/revisions\/3638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/media\/3637"}],"wp:attachment":[{"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/media?parent=3636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/categories?post=3636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staysafe.aero\/fr\/wp-json\/wp\/v2\/tags?post=3636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}